{"id":456,"date":"2016-05-16T13:36:24","date_gmt":"2016-05-16T12:36:24","guid":{"rendered":"https:\/\/wpmanager.buffet-group.com\/scherzer\/ja\/?page_id=456"},"modified":"2018-03-27T07:57:44","modified_gmt":"2018-03-27T06:57:44","slug":"home","status":"publish","type":"page","link":"https:\/\/www.scherzer-trumpets.com\/ja\/","title":{"rendered":"Home"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_relevanssi_hide_post":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","footnotes":""},"class_list":["post-456","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Home - J. Scherzer<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.scherzer-trumpets.com\/ja\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Home - J. Scherzer\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.scherzer-trumpets.com\/ja\/\" \/>\n<meta property=\"og:site_name\" content=\"J. Scherzer\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/JScherzer\" \/>\n<meta property=\"article:modified_time\" content=\"2018-03-27T06:57:44+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.scherzer-trumpets.com\\\/ja\\\/\",\"url\":\"https:\\\/\\\/www.scherzer-trumpets.com\\\/ja\\\/\",\"name\":\"Home - J. Scherzer\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/www.scherzer-trumpets.com\\\/en\\\/#website\"},\"datePublished\":\"2016-05-16T12:36:24+00:00\",\"dateModified\":\"2018-03-27T06:57:44+00:00\",\"inLanguage\":\"ja-JA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.scherzer-trumpets.com\\\/ja\\\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/www.scherzer-trumpets.com\\\/en\\\/#website\",\"url\":\"http:\\\/\\\/www.scherzer-trumpets.com\\\/en\\\/\",\"name\":\"J. Scherzer\",\"description\":\"\",\"publisher\":{\"@id\":\"http:\\\/\\\/www.scherzer-trumpets.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/www.scherzer-trumpets.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ja-JA\"},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/www.scherzer-trumpets.com\\\/en\\\/#organization\",\"name\":\"J. Scherzer\",\"url\":\"http:\\\/\\\/www.scherzer-trumpets.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ja-JA\",\"@id\":\"http:\\\/\\\/www.scherzer-trumpets.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/wpmanager.buffet-group.com\\\/scherzer\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/05\\\/scherzer_b.png\",\"contentUrl\":\"https:\\\/\\\/wpmanager.buffet-group.com\\\/scherzer\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2016\\\/05\\\/scherzer_b.png\",\"width\":232,\"height\":232,\"caption\":\"J. Scherzer\"},\"image\":{\"@id\":\"http:\\\/\\\/www.scherzer-trumpets.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/JScherzer\",\"http:\\\/\\\/www.youtube.com\\\/user\\\/bandsbrass\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Home - J. Scherzer","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.scherzer-trumpets.com\/ja\/","og_locale":"en_US","og_type":"article","og_title":"Home - J. Scherzer","og_url":"https:\/\/www.scherzer-trumpets.com\/ja\/","og_site_name":"J. Scherzer","article_publisher":"https:\/\/www.facebook.com\/JScherzer","article_modified_time":"2018-03-27T06:57:44+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.scherzer-trumpets.com\/ja\/","url":"https:\/\/www.scherzer-trumpets.com\/ja\/","name":"Home - J. Scherzer","isPartOf":{"@id":"http:\/\/www.scherzer-trumpets.com\/en\/#website"},"datePublished":"2016-05-16T12:36:24+00:00","dateModified":"2018-03-27T06:57:44+00:00","inLanguage":"ja-JA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.scherzer-trumpets.com\/ja\/"]}]},{"@type":"WebSite","@id":"http:\/\/www.scherzer-trumpets.com\/en\/#website","url":"http:\/\/www.scherzer-trumpets.com\/en\/","name":"J. Scherzer","description":"","publisher":{"@id":"http:\/\/www.scherzer-trumpets.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/www.scherzer-trumpets.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ja-JA"},{"@type":"Organization","@id":"http:\/\/www.scherzer-trumpets.com\/en\/#organization","name":"J. Scherzer","url":"http:\/\/www.scherzer-trumpets.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"ja-JA","@id":"http:\/\/www.scherzer-trumpets.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/wpmanager.buffet-group.com\/scherzer\/wp-content\/uploads\/sites\/11\/2016\/05\/scherzer_b.png","contentUrl":"https:\/\/wpmanager.buffet-group.com\/scherzer\/wp-content\/uploads\/sites\/11\/2016\/05\/scherzer_b.png","width":232,"height":232,"caption":"J. Scherzer"},"image":{"@id":"http:\/\/www.scherzer-trumpets.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/JScherzer","http:\/\/www.youtube.com\/user\/bandsbrass"]}]}},"_links":{"self":[{"href":"https:\/\/www.scherzer-trumpets.com\/ja\/wp-json\/wp\/v2\/pages\/456","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.scherzer-trumpets.com\/ja\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.scherzer-trumpets.com\/ja\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.scherzer-trumpets.com\/ja\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.scherzer-trumpets.com\/ja\/wp-json\/wp\/v2\/comments?post=456"}],"version-history":[{"count":1,"href":"https:\/\/www.scherzer-trumpets.com\/ja\/wp-json\/wp\/v2\/pages\/456\/revisions"}],"predecessor-version":[{"id":460,"href":"https:\/\/www.scherzer-trumpets.com\/ja\/wp-json\/wp\/v2\/pages\/456\/revisions\/460"}],"wp:attachment":[{"href":"https:\/\/www.scherzer-trumpets.com\/ja\/wp-json\/wp\/v2\/media?parent=456"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}